{"id":10590,"date":"2025-05-08T08:55:58","date_gmt":"2025-05-08T12:55:58","guid":{"rendered":"https:\/\/www.afmc.ca\/?p=10590"},"modified":"2025-06-18T16:49:59","modified_gmt":"2025-06-18T20:49:59","slug":"afmc-statement-on-u-s-reforms-to-medical-school-accreditation","status":"publish","type":"post","link":"https:\/\/www.afmc.ca\/fr\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/","title":{"rendered":"D\u00e9claration de l'AFMC sur les r\u00e9formes am\u00e9ricaines relatives \u00e0 l'agr\u00e9ment des facult\u00e9s de m\u00e9decine"},"content":{"rendered":"<p>May 8, 2025<\/p>\n<p>\u00a0<\/p>\n\n<p><strong>Responsabilit\u00e9 sociale des facult\u00e9s de m\u00e9decine<\/strong><\/p>\n<p>\u00a0<\/p>\n\n<p>Selon l\u2019Organisation mondiale de la sant\u00e9 (OMS), en ce qui a trait \u00e0 la responsabilit\u00e9 sociale, les facult\u00e9s de m\u00e9decine ont \u00ab l\u2019obligation d\u2019axer leurs activit\u00e9s d\u2019enseignement, de recherche et de services sur les pr\u00e9occupations prioritaires en mati\u00e8re de sant\u00e9 de la communaut\u00e9, de la r\u00e9gion et de la nation qu\u2019elles ont le mandat de servir.<\/p>\n<p>\u00a0<\/p>\n\n<p>Les facult\u00e9s de m\u00e9decine canadiennes ont donc un r\u00f4le important \u00e0 jouer pour garantir que le syst\u00e8me de sant\u00e9 canadien, tr\u00e8s appr\u00e9ci\u00e9, continue d'offrir des soins accessibles et de qualit\u00e9 qui r\u00e9pondent aux besoins changeants des populations diversifi\u00e9es du Canada.\n\u00c0 cette fin, des normes d'agr\u00e9ment en mati\u00e8re d'\u00e9quit\u00e9, de diversit\u00e9 et d'inclusion (EDI) sont essentielles au sein du paysage m\u00e9dical canadien.<\/p>\n<p>\u00a0<\/p>\n\n<p>Ces normes garantissent que les programmes d'\u00e9tudes en m\u00e9decine couvrent les th\u00e8mes fondamentaux li\u00e9s \u00e0 l'\u00e9quit\u00e9 en mati\u00e8re de sant\u00e9. Elles contribuent \u00e9galement \u00e0 garantir que des candidats qualifi\u00e9s issus de diverses populations puissent acc\u00e9der \u00e0 la formation m\u00e9dicale et, \u00e0 terme, fa\u00e7onner un syst\u00e8me de sant\u00e9 qui r\u00e9pond aux besoins des Canadiens.<\/p>\n<p>\u00a0<\/p>\n\n<p>L'AFMC donne la priorit\u00e9 aux initiatives qui permettront aux facult\u00e9s de m\u00e9decine et au syst\u00e8me de sant\u00e9 de mieux venir en aide aux populations qui m\u00e9ritent d'\u00eatre trait\u00e9es avec \u00e9quit\u00e9.<\/p>\n<p>\u00a0<\/p>\n\n<p><strong>D\u00e9cret pr\u00e9sidentiel am\u00e9ricain<\/strong><\/p>\n<p>\u00a0<\/p>\n\n<p>Le 23 avril 2025, le pr\u00e9sident am\u00e9ricain Donald Trump a publi\u00e9 un d\u00e9cret rendant ill\u00e9gal pour les organismes d'agr\u00e9ment aux \u00c9tats-Unis d'inclure des exigences en mati\u00e8re d'\u00e9quit\u00e9, de diversit\u00e9 et d'inclusion dans le processus d'agr\u00e9ment des<ins> <\/ins>facult\u00e9s de m\u00e9decine am\u00e9ricaines <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/04\/reforming-accreditation-to-strengthen-higher-education\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>(Reforming Accreditation to Strengthen Higher Education, Section 2(c)<\/em><\/a><em>.<\/em><\/p>\n<p>\u00a0<\/p>\n\n<p>En tant que porte-parole de la m\u00e9decine universitaire au Canada, l'AFMC est profond\u00e9ment pr\u00e9occup\u00e9e par cette d\u00e9cision et par ses r\u00e9percussions n\u00e9gatives sur l'acc\u00e8s \u00e0 l'\u00e9ducation, la diversit\u00e9 au sein de la profession m\u00e9dicale et l'acc\u00e8s aux soins pour les populations m\u00e9ritant l'\u00e9quit\u00e9 aux \u00c9tats-Unis.<\/p>\n<p>\u00a0<\/p>\n\n<p>Le d\u00e9cret du pr\u00e9sident Trump est en contradiction directe avec la <a href=\"https:\/\/www.afmc.ca\/fr\/strategic-priorities\/social-accountability\/edi-and-anti-racism\/\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9claration de l\u2019AFMC contre la discrimination<\/a> ainsi que la <a href=\"https:\/\/www.afmc.ca\/wp-content\/uploads\/2025\/03\/Declaration_contre_le_racisme_2025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9claration d\u2019engagement des facult\u00e9s de m\u00e9decine canadienne \u00e0 lutter contre le racisme<\/a>.<\/p>\n<p>\u00a0<\/p>\n\n<p><strong>Normes d\u2019agr\u00e9ment des facult\u00e9s de m\u00e9decine canadiennes<\/strong><\/p>\n<p>\u00a0<\/p>\n\n<p>Avant 1979, les programmes de m\u00e9decine canadiens \u00e9taient agr\u00e9\u00e9s par <em>l'American Liaison Committee on Medical Education<\/em> (LCME). En 1979, le Canada a cr\u00e9\u00e9 son propre organisme d'agr\u00e9ment, le Comit\u00e9 d'agr\u00e9ment des facult\u00e9s de m\u00e9decine du Canada <em>Comit\u00e9 d\u2019agr\u00e9ment des facult\u00e9s de m\u00e9decine du Canada<\/em> (CAFMC).<\/p>\n<p>\u00a0<\/p>\n\n<p>L'\u00e9dition 2026 du <em>F\u00e9d\u00e9ration mondiale pour l'\u00e9ducation m\u00e9dicale<\/em> (WFME) reconna\u00eet le CAFMC comme un organisme d'agr\u00e9ment ind\u00e9pendant pour les programmes de m\u00e9decine au Canada. Les facult\u00e9s de m\u00e9decine canadiennes sont donc inscrites dans le r\u00e9pertoire mondial des organismes qui reconnaissent ou accordent l'agr\u00e9ment aux facult\u00e9s de m\u00e9decine.<del><\/del><\/p>\n<p>\u00a0<\/p>\n\n<p>Pour des raisons historiques, les programmes de m\u00e9decine canadiens ont continu\u00e9 de recevoir le double agr\u00e9ment du CAFMC et du LCME, permettant ainsi aux dipl\u00f4m\u00e9s en m\u00e9decine canadiens de faire leur r\u00e9sidence et leur stage de sp\u00e9cialisation aux \u00c9tats-Unis.<\/p>\n<p>\u00a0<\/p>\n\n<p>La responsabilit\u00e9 sociale est devenue une norme d'agr\u00e9ment officielle au Canada en 2015, et la premi\u00e8re application de ces normes a \u00e9t\u00e9 mise en \u0153uvre en 2017. Cette modification des normes d'agr\u00e9ment du premier cycle a marqu\u00e9 un tournant important vers une plus grande responsabilit\u00e9 des facult\u00e9s de m\u00e9decine canadiennes pour r\u00e9pondre aux besoins de leurs communaut\u00e9s en mati\u00e8re de sant\u00e9.<\/p>\n<p>\u00a0<\/p>\n\n<p>Par la suite, le LCME a cess\u00e9 d'accorder l'agr\u00e9ment aux facult\u00e9s de m\u00e9decine canadiennes. \u00c0 compter du 1<sup>er<\/sup>juillet 2025, les facult\u00e9s de m\u00e9decine canadiennes ne seront agr\u00e9\u00e9es que par le CAFMC.<\/p>\n<p>\u00a0<\/p>\n\n<p>\u00c0 compter du 1er juillet 2025, les dipl\u00f4m\u00e9s des facult\u00e9s de m\u00e9decine canadiennes qui souhaitent suivre une formation m\u00e9dicale sup\u00e9rieure aux \u00c9tats-Unis,<sup>er<\/sup>y compris les candidats \u00e0 un poste de moniteur (fellow), seront consid\u00e9r\u00e9s comme des dipl\u00f4m\u00e9s internationaux en m\u00e9decine (DIM).<\/p>\n<p>\u00a0<\/p>\n\n<p><strong>R\u00e9percussions sur les apprenant(e)s<\/strong><\/p>\n<p>\u00a0<\/p>\n\n<p>Le r\u00e9cent d\u00e9cret du pr\u00e9sident Trump est tr\u00e8s inqui\u00e9tant et aura de graves r\u00e9percussions sur l'ensemble du syst\u00e8me de sant\u00e9 am\u00e9ricain.<\/p>\n<p>\u00a0<\/p>\n\n<p>Les donn\u00e9es les plus r\u00e9centes montrent que moins de 0,1 % des m\u00e9decins canadiens poursuivent leur r\u00e9sidence \u00e0 l'\u00e9tranger (<a href=\"https:\/\/view.officeapps.live.com\/op\/view.aspx?src=https%3A%2F%2Fwww.cihi.ca%2Fsites%2Fdefault%2Ffiles%2Frot%2Fsupply-distribution-migration-physicians-in-canada-2022-data-tables-en.xlsx&amp;wdOrigin=BROWSELINK\" target=\"_blank\" rel=\"noreferrer noopener\">Institut canadien d\u2019information sur la sant\u00e9. <em>Nombre, r\u00e9partition et migration des m\u00e9decins au Canada, 2022 \u2014 Tableaux de donn\u00e9es.<\/em>Ottawa, ON: ICIS; 2023<\/a>).<\/p>\n<p>\u00a0<\/p>\n\n<p>Au cours des cinq derni\u00e8res ann\u00e9es, le nombre de dipl\u00f4m\u00e9s en m\u00e9decine canadiens (DMC) qui ont cherch\u00e9 \u00e0 faire leur r\u00e9sidence aux \u00c9tats-Unis a diminu\u00e9. En 2021, seulement 22 DMC ont pr\u00e9sent\u00e9 une demande de r\u00e9sidence aux \u00c9tats-Unis et sept ont \u00e9t\u00e9 jumel\u00e9s. En 2025, seulement 15 DMC ont pr\u00e9sent\u00e9 une demande de r\u00e9sidence aux \u00c9tats-Unis et dix ont \u00e9t\u00e9 jumel\u00e9s (<a href=\"https:\/\/www.nrmp.org\/wp-content\/uploads\/2025\/03\/Advance_Data_Tables_2025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Advance Data Tables for the 2025 Main Residency Match, Table 4).<\/a><\/p>\n<p>\u00a0<\/p>\n\n<p>L'AFMC demeure fi\u00e8re du syst\u00e8me canadien de formation m\u00e9dicale, convaincue de la pertinence des normes d'agr\u00e9ment du CAFMC et d\u00e9termin\u00e9e \u00e0 promouvoir l'importance de la responsabilit\u00e9 sociale de nos syst\u00e8mes de sant\u00e9.<\/p>\n<p>\u00a0<\/p>\n\n<p>Vous pouvez adresser toute question ou suggestion concernant cette situation en constante \u00e9volution \u00e0 l'adresse suivante : <a href=\"mailto:communications@afmc.ca\">communications@afmc.ca<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>May 8, 2025 \u00a0 Social Accountability of Medical Schools \u00a0 According to the World Health Organization (WHO), the social accountability of medical schools is \u201cthe obligation to direct their education, research and service activities towards addressing the priority health concerns of the community, region, and\/or nation they have a mandate to serve.\u201d \u00a0 Canadian medical [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10590","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AFMC Statement on U.S. Reforms to Medical School Accreditation - AFMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.afmc.ca\/fr\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFMC Statement on U.S. Reforms to Medical School Accreditation - AFMC\" \/>\n<meta property=\"og:description\" content=\"May 8, 2025 \u00a0 Social Accountability of Medical Schools \u00a0 According to the World Health Organization (WHO), the social accountability of medical schools is \u201cthe obligation to direct their education, research and service activities towards addressing the priority health concerns of the community, region, and\/or nation they have a mandate to serve.\u201d \u00a0 Canadian medical [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.afmc.ca\/fr\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/\" \/>\n<meta property=\"og:site_name\" content=\"AFMC\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-08T12:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T20:49:59+00:00\" \/>\n<meta name=\"author\" content=\"addmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AFMC_e\" \/>\n<meta name=\"twitter:site\" content=\"@AFMC_e\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"addmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/\"},\"author\":{\"name\":\"addmin\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/person\\\/8040515ab2bd5e2dbfef12c7e9a762e3\"},\"headline\":\"AFMC Statement on U.S. Reforms to Medical School Accreditation\",\"datePublished\":\"2025-05-08T12:55:58+00:00\",\"dateModified\":\"2025-06-18T20:49:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/\"},\"wordCount\":659,\"publisher\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/\",\"name\":\"AFMC Statement on U.S. Reforms to Medical School Accreditation - AFMC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#website\"},\"datePublished\":\"2025-05-08T12:55:58+00:00\",\"dateModified\":\"2025-06-18T20:49:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.afmc.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AFMC Statement on U.S. Reforms to Medical School Accreditation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/\",\"name\":\"AFMC\",\"description\":\"The academic partner for Canada\u2019s faculties of medicine.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.afmc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\",\"name\":\"The Association of Faculties of Medicine of Canada\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AFMC-Flywheel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AFMC-Flywheel.jpg\",\"width\":904,\"height\":536,\"caption\":\"The Association of Faculties of Medicine of Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AFMC_e\",\"https:\\\/\\\/www.instagram.com\\\/afmc.ca\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/the-association-of-faculties-of-medicine-of-canada\\\/?originalSubdomain=ca\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC02Np2Hp_mw-Tr5gR_y24pg?view_as=subscriber\",\"https:\\\/\\\/twitter.com\\\/AFMC_f\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/person\\\/8040515ab2bd5e2dbfef12c7e9a762e3\",\"name\":\"addmin\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/fr\\\/author\\\/addmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AFMC Statement on U.S. Reforms to Medical School Accreditation - AFMC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.afmc.ca\/fr\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/","og_locale":"fr_CA","og_type":"article","og_title":"AFMC Statement on U.S. Reforms to Medical School Accreditation - AFMC","og_description":"May 8, 2025 \u00a0 Social Accountability of Medical Schools \u00a0 According to the World Health Organization (WHO), the social accountability of medical schools is \u201cthe obligation to direct their education, research and service activities towards addressing the priority health concerns of the community, region, and\/or nation they have a mandate to serve.\u201d \u00a0 Canadian medical [&hellip;]","og_url":"https:\/\/www.afmc.ca\/fr\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/","og_site_name":"AFMC","article_published_time":"2025-05-08T12:55:58+00:00","article_modified_time":"2025-06-18T20:49:59+00:00","author":"addmin","twitter_card":"summary_large_image","twitter_creator":"@AFMC_e","twitter_site":"@AFMC_e","twitter_misc":{"\u00c9crit par":"addmin","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/#article","isPartOf":{"@id":"https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/"},"author":{"name":"addmin","@id":"https:\/\/www.afmc.ca\/#\/schema\/person\/8040515ab2bd5e2dbfef12c7e9a762e3"},"headline":"AFMC Statement on U.S. Reforms to Medical School Accreditation","datePublished":"2025-05-08T12:55:58+00:00","dateModified":"2025-06-18T20:49:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/"},"wordCount":659,"publisher":{"@id":"https:\/\/www.afmc.ca\/#organization"},"articleSection":["News"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/","url":"https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/","name":"AFMC Statement on U.S. Reforms to Medical School Accreditation - AFMC","isPartOf":{"@id":"https:\/\/www.afmc.ca\/#website"},"datePublished":"2025-05-08T12:55:58+00:00","dateModified":"2025-06-18T20:49:59+00:00","breadcrumb":{"@id":"https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.afmc.ca\/afmc-statement-on-u-s-reforms-to-medical-school-accreditation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.afmc.ca\/"},{"@type":"ListItem","position":2,"name":"AFMC Statement on U.S. Reforms to Medical School Accreditation"}]},{"@type":"WebSite","@id":"https:\/\/www.afmc.ca\/#website","url":"https:\/\/www.afmc.ca\/","name":"l\u2019AFMC","description":"The academic partner for Canada\u2019s faculties of medicine.","publisher":{"@id":"https:\/\/www.afmc.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.afmc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.afmc.ca\/#organization","name":"Association des facult\u00e9s de m\u00e9decine du Canada","url":"https:\/\/www.afmc.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.afmc.ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/09\/AFMC-Flywheel.jpg","contentUrl":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/09\/AFMC-Flywheel.jpg","width":904,"height":536,"caption":"The Association of Faculties of Medicine of Canada"},"image":{"@id":"https:\/\/www.afmc.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AFMC_e","https:\/\/www.instagram.com\/afmc.ca\/","https:\/\/www.linkedin.com\/company\/the-association-of-faculties-of-medicine-of-canada\/?originalSubdomain=ca","https:\/\/www.youtube.com\/channel\/UC02Np2Hp_mw-Tr5gR_y24pg?view_as=subscriber","https:\/\/twitter.com\/AFMC_f"]},{"@type":"Person","@id":"https:\/\/www.afmc.ca\/#\/schema\/person\/8040515ab2bd5e2dbfef12c7e9a762e3","name":"addmin","url":"https:\/\/www.afmc.ca\/fr\/author\/addmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/10590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/comments?post=10590"}],"version-history":[{"count":7,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/10590\/revisions"}],"predecessor-version":[{"id":10775,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/10590\/revisions\/10775"}],"wp:attachment":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/media?parent=10590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/categories?post=10590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/tags?post=10590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}