{"id":8898,"date":"2023-11-15T14:33:38","date_gmt":"2023-11-15T19:33:38","guid":{"rendered":"https:\/\/www.afmc.ca\/?p=8898"},"modified":"2023-11-15T14:33:38","modified_gmt":"2023-11-15T19:33:38","slug":"learners-news-november-2023","status":"publish","type":"post","link":"https:\/\/www.afmc.ca\/fr\/learners-news-november-2023\/","title":{"rendered":"Nouvelles \u00e0 l\u2019intention des apprenants \u2013 Novembre 2023\u00a0"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Calendriers du jumelage<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Les calendriers relatifs au jumelage R1 de 2021 \u00e0 2024 ont fait l'objet d'importantes modifications dues \u00e0 la n\u00e9cessit\u00e9 de tenir compte des modifications apport\u00e9es au programme d'\u00e9tudes dans les facult\u00e9s de m\u00e9decine au cours des ann\u00e9es de pand\u00e9mie. Ces modifications ont eu pour effet de comprimer les d\u00e9lais, ce qui a mis \u00e0 rude \u00e9preuve les unit\u00e9s de formation postdoctorale et les programmes de r\u00e9sidence dans tous les aspects du jumelage. En outre, l'AFMC a re\u00e7u des commentaires de la part de la FOMC au sujet des difficult\u00e9s caus\u00e9es par le \u00ab calendrier en p\u00e9riode de pand\u00e9mie \u00bb pour les organismes de d\u00e9livrance des permis. Par ailleurs, les gouvernements provinciaux et f\u00e9d\u00e9ral ont fait part \u00e0 l'AFMC de leur souhait d'une meilleure harmonisation avec le jumelage du NRMP aux \u00c9tats-Unis, afin de maximiser la capacit\u00e9 des Canadiens en formation \u00e0 l'\u00e9tranger \u00e0 revenir au Canada. Les unit\u00e9s d\u2019EMPr demandent un retour \u00e0 la pratique ant\u00e9rieure \u00e0 la pand\u00e9mie, qui consistait \u00e0 fixer les calendriers de jumelage longtemps \u00e0 l'avance (au lieu d'une ann\u00e9e \u00e0 la fois) afin de faciliter l'\u00e9tablissement des programmes d'\u00e9tudes et leur approbation par les conseils respectifs.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Lors de la r\u00e9union du Conseil d'administration de l'AFMC du 24 octobre 2023, le Conseil d'administration de l'AFMC a approuv\u00e9 les calendriers suivants :<\/p>\n\n\n\n<p>Voici les dates du calendrier de jumelage pour 2025 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date limite de pr\u00e9sentation du DREM\/relev\u00e9 de notes (ne n\u00e9cessitant pas de traduction) : le vendredi 15 novembre 2024<sup>th<\/sup>, 2024\u00a0<\/li>\n\n\n\n<li>Date limite de d\u00e9p\u00f4t des candidatures : le vendredi 29 novembre 2024<sup>th<\/sup>, 2024\u00a0<\/li>\n\n\n\n<li>P\u00e9riode d'examen des dossiers : du vendredi 29 novembre 2024 au mardi 14 janvier 2025\u00a0<\/li>\n\n\n\n<li>P\u00e9riode des entrevues : du samedi 18 janvier 2025 au dimanche 9 f\u00e9vrier 2025\u00a0<\/li>\n\n\n\n<li>Premier tour du jumelage : le mardi 4 mars 2025\u00a0<\/li>\n\n\n\n<li>Deuxi\u00e8me tour du jumelage : le jeudi 17 avril 2025\u00a0<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Voici les dates du calendrier de jumelage pour 2026 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\uf0a7\tDate limite de pr\u00e9sentation du DREM\/relev\u00e9 de notes (ne n\u00e9cessitant pas de traduction) : le vendredi 14 novembre 2025<sup>th<\/sup>, 2025\u00a0<\/li>\n\n\n\n<li>Date limite de d\u00e9p\u00f4t des candidatures : le jeudi 27 novembre 2025\u00a0<\/li>\n\n\n\n<li>P\u00e9riode d'examen des dossiers : du jeudi 27 novembre 2025 au mardi 13 janvier 2026\u00a0<\/li>\n\n\n\n<li>P\u00e9riode des entrevues : du samedi 17 janvier 2026 au dimanche 8 f\u00e9vrier 2026\u00a0<\/li>\n\n\n\n<li>Premier tour du jumelage : le mardi 3 mars 2026\u00a0<\/li>\n\n\n\n<li>Deuxi\u00e8me tour du jumelage : le mardi 21 avril 2026\u00a0<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Voici les dates du calendrier de jumelage pour 2027 :\u00a0\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Date limite de pr\u00e9sentation du DREM\/relev\u00e9 de notes (ne n\u00e9cessitant pas de traduction) : le vendredi 13 novembre 2026\u00a0<\/li>\n\n\n\n<li>Date limite de d\u00e9p\u00f4t des candidatures : le jeudi 26 novembre 2026\u00a0<\/li>\n\n\n\n<li>P\u00e9riode d'examen des dossiers : du jeudi 26 novembre 2026 au mardi 12 janvier 2027\u00a0<\/li>\n\n\n\n<li>P\u00e9riode des entrevues : du samedi 16 janvier 2027 au dimanche 7 f\u00e9vrier 2027\u00a0<\/li>\n\n\n\n<li>Premier tour du jumelage : le mardi 2 mars 2027\u00a0<\/li>\n\n\n\n<li>Deuxi\u00e8me tour du jumelage : le mardi 20 avril 2027\u00a0<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Lettres de recommandation<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Lors de la r\u00e9union du Conseil d'administration de l'AFMC qui s'est tenue le 24 octobre 2023, les membres du Conseil ont approuv\u00e9 la recommandation du Comit\u00e9 de l'AFMC sur l'enseignement m\u00e9dical pr\u00e9doctoral et du Comit\u00e9 permanent sur l'\u00e9ducation (CPE) visant \u00e0 maintenir l'approche actuelle concernant l'utilisation des lettres de recommandation dans le cadre du jumelage R1.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Alors que les facult\u00e9s de m\u00e9decine du Canada continuent d'augmenter le nombre de stages \u00e0 option disponibles pour les \u00e9tudiants, il subsiste des in\u00e9galit\u00e9s dans l'acc\u00e8s aux stages \u00e0 option pour \u00e9tudiants visiteurs. Conscient de cette situation, le Comit\u00e9 de l'AFMC sur l\u2019EMPr a demand\u00e9 au CPE et au Conseil d'administration d'appuyer l'utilisation continue des lignes directrices relatives aux lettres de recommandation qui ont \u00e9t\u00e9 \u00e9labor\u00e9es pendant la pand\u00e9mie.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Concernant l'utilisation des documents de r\u00e9f\u00e9rence pour les prochains jumelages R-1 :\u00a0\u00a0<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"1\">\n<li>Des lettres de recommandation structur\u00e9es doivent \u00eatre remplies par les r\u00e9f\u00e9rents pour les trois disciplines suivantes : m\u00e9decine familiale, m\u00e9decine d\u2019urgence et chirurgie orthop\u00e9dique. Les autres disciplines peuvent demander une lettre de recommandation traditionnelle ou un formulaire d\u2019appui au candidat (cr\u00e9\u00e9 par les programmes individuels). Les exigences en mati\u00e8re de r\u00e9f\u00e9rences se trouvent dans les descriptions des programmes sur <a href=\"https:\/\/link.edgepilot.com\/s\/81f350c0\/1OSzM-w6BkOLn7AdZiSC3A?u=http:\/\/carms.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">carms.ca.<\/a>.\u00a0\u00a0\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\">\n<li>Des documents de r\u00e9f\u00e9rence provenant de l\u2019\u00e9tablissement auquel le candidat postule ne doivent pas constituer un crit\u00e8re pour l\u2019examen du dossier ni, au final, pour le classement.\u00a0\u00a0\u00a0\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\">\n<li>Il ne sera pas n\u00e9cessaire d\u2019obtenir un document de r\u00e9f\u00e9rence propre \u00e0 la discipline \u00e0 laquelle le candidat postule.\u00a0\u00a0\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\">\n<li>Chaque programme peut demander \u00e0 un candidat un maximum de trois (3) lettres de recommandation.\u00a0<\/li>\n<\/ol>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Renseignements suppl\u00e9mentaires concernant la lettre d\u2019appui<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"5\">\n<li>\u00a0La lettre d'appui est utilis\u00e9e exclusivement par les facult\u00e9s de m\u00e9decine de langue fran\u00e7aise du Qu\u00e9bec et est souvent demand\u00e9e \u00e0 la place d'une lettre de recommandation lors de l'inscription aux programmes de r\u00e9sidence de ces facult\u00e9s.\u00a0\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"6\">\n<li>\u00a0\u00c9tant donn\u00e9 que la lettre d'appui constitue, dans sa forme actuelle, un formulaire normalis\u00e9 et qu'elle b\u00e9n\u00e9ficie du soutien de tous les groupes d'intervenants de ces facult\u00e9s, aucun changement n'est sugg\u00e9r\u00e9 quant au contenu ou \u00e0 la structure de ladite lettre d'appui.<\/li>\n<\/ol>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Entrevues synchrones ou asynchrones<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>L'exp\u00e9rience de ces derni\u00e8res ann\u00e9es et la documentation publi\u00e9e confirment que rien ne permet actuellement d'affirmer la sup\u00e9riorit\u00e9 d'une m\u00e9thode d'entrevue par rapport \u00e0 l'autre. Chaque programme doit donc d\u00e9cider de la m\u00e9thode \u00e0 utiliser en fonction de ses besoins locaux et de ses meilleures pratiques; aucune politique nationale ne sera impos\u00e9e.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Aper\u00e7u de l\u2019enqu\u00eate sur le Questionnaire de d\u00e9claration volontaire de CaRMS (QDVC)<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Contexte<\/strong><\/p>\n\n\n\n<p>CaRMS a \u00e9labor\u00e9 le QDVC en r\u00e9ponse aux demandes des clients et des intervenants qui souhaitaient combler une lacune sur le plan des donn\u00e9es dans le processus de s\u00e9lection, notamment en ce qui a trait \u00e0 la diversit\u00e9. Le QDVC vise deux objectifs : recueillir des donn\u00e9es sur la diversit\u00e9 et soutenir les programmes visant \u00e0 visant \u00e0 int\u00e9grer la notion de diversit\u00e9 dans le processus de s\u00e9lection.\nL'AFMC a re\u00e7u de pr\u00e9cieux commentaires de la part des f\u00e9d\u00e9rations d'apprenants quant \u00e0 l'utilisation du QDVC, qui ont mis en lumi\u00e8re diverses pr\u00e9occupations concernant sa mise en pratique, faisant \u00e9cho aux inqui\u00e9tudes partag\u00e9es par le Comit\u00e9 permanent de l'AFMC sur la responsabilit\u00e9 sociale. L'une des principales appr\u00e9hensions concerne l'utilisation abusive potentielle des donn\u00e9es du QDVC. Les recommandations ont propos\u00e9 l'int\u00e9gration de mesures de protection contre l'utilisation abusive et la formation des personnes qui g\u00e8rent les donn\u00e9es en vue d'une utilisation appropri\u00e9e. En ao\u00fbt 2023, le Comit\u00e9 permanent de l'AFMC sur la responsabilit\u00e9 sociale a men\u00e9 une enqu\u00eate de suivi sur le QDVC aupr\u00e8s des doyens de l\u2019EMPo, afin d'obtenir des \u00e9claircissements sur leurs proc\u00e9dures et initiatives de formation li\u00e9es au QDVC.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Aper\u00e7u des r\u00e9sultats<\/strong>\u00a0<\/p>\n\n\n\n<p>D'apr\u00e8s les commentaires re\u00e7us, certaines facult\u00e9s de m\u00e9decine sont encore en train d'\u00e9valuer les avantages de l'utilisation du QDVC et ne l'ont donc pas adopt\u00e9. Celles qui ont choisi de recourir au QDVC ont mis en place des mesures pour veiller \u00e0 ce que le personnel des programmes concern\u00e9s soit correctement form\u00e9. Les facult\u00e9s de m\u00e9decine qui utilisent le QDVC exigent que les programmes suivent une formation sur les partis pris et\/ou l'EDI avant de l'utiliser. En outre, le personnel universitaire et les consultants des facult\u00e9s participantes poss\u00e8dent des qualifications en mati\u00e8re d'EDI qui influencent l'\u00e9laboration des politiques, la mise en \u0153uvre et la formation relatives \u00e0 l'utilisation du QDVC. Le Comit\u00e9 permanent de l'AFMC sur la responsabilit\u00e9 sociale a formul\u00e9 des recommandations \u00e0 ce sujet et collaborera avec les unit\u00e9s d'EMPo dans les facult\u00e9s de m\u00e9decine afin d'\u00e9tudier la question. L'engagement continu et les consultations avec les apprenants ont \u00e9t\u00e9 essentiels pour parvenir \u00e0 des recommandations de meilleures pratiques que les unit\u00e9s d'EMPo se sont engag\u00e9es \u00e0 revoir et \u00e0 int\u00e9grer.\u00a0<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>L'AFMC, en collaboration avec les facult\u00e9s de m\u00e9decine, s'attache \u00e0 peaufiner la mise en \u0153uvre du QDVC en partageant les exp\u00e9riences, en garantissant les meilleures pratiques et en encourageant les dialogues qui int\u00e8grent les points de vue des \u00e9tudiants, du corps professoral et de l'ensemble de la communaut\u00e9.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Match timelines The 2021-2024 R1 Match timelines have seen significant changes due to the need to accommodate change in curriculum delivery in medical schools during the peri- pandemic years. This resulted in compressed timelines that stressed the postgraduate offices and residency programs in all aspects of the match. In addition, the AFMC received feedback from [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[12],"class_list":["post-8898","post","type-post","status-publish","format-standard","hentry","category-news","tag-learners"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Learners News: November 2023\u00a0 - AFMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.afmc.ca\/fr\/learners-news-november-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Learners News: November 2023\u00a0 - AFMC\" \/>\n<meta property=\"og:description\" content=\"Match timelines The 2021-2024 R1 Match timelines have seen significant changes due to the need to accommodate change in curriculum delivery in medical schools during the peri- pandemic years. This resulted in compressed timelines that stressed the postgraduate offices and residency programs in all aspects of the match. In addition, the AFMC received feedback from [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.afmc.ca\/fr\/learners-news-november-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"AFMC\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-15T19:33:38+00:00\" \/>\n<meta name=\"author\" content=\"Fatou Thioune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AFMC_e\" \/>\n<meta name=\"twitter:site\" content=\"@AFMC_e\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fatou Thioune\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/\"},\"author\":{\"name\":\"Fatou Thioune\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/person\\\/e8e6ce9828f441168a40cdf0d821bab2\"},\"headline\":\"Learners News: November 2023\u00a0\",\"datePublished\":\"2023-11-15T19:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/\"},\"wordCount\":1017,\"publisher\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\"},\"keywords\":[\"Learners\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/\",\"name\":\"Learners News: November 2023\u00a0 - AFMC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#website\"},\"datePublished\":\"2023-11-15T19:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/learners-news-november-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.afmc.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learners News: November 2023\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/\",\"name\":\"AFMC\",\"description\":\"The academic partner for Canada\u2019s faculties of medicine.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.afmc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\",\"name\":\"The Association of Faculties of Medicine of Canada\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AFMC-Flywheel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AFMC-Flywheel.jpg\",\"width\":904,\"height\":536,\"caption\":\"The Association of Faculties of Medicine of Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AFMC_e\",\"https:\\\/\\\/www.instagram.com\\\/afmc.ca\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/the-association-of-faculties-of-medicine-of-canada\\\/?originalSubdomain=ca\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC02Np2Hp_mw-Tr5gR_y24pg?view_as=subscriber\",\"https:\\\/\\\/twitter.com\\\/AFMC_f\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/person\\\/e8e6ce9828f441168a40cdf0d821bab2\",\"name\":\"Fatou Thioune\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/fr\\\/author\\\/fthiouneafmc-ca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Learners News: November 2023\u00a0 - AFMC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.afmc.ca\/fr\/learners-news-november-2023\/","og_locale":"fr_CA","og_type":"article","og_title":"Learners News: November 2023\u00a0 - AFMC","og_description":"Match timelines The 2021-2024 R1 Match timelines have seen significant changes due to the need to accommodate change in curriculum delivery in medical schools during the peri- pandemic years. This resulted in compressed timelines that stressed the postgraduate offices and residency programs in all aspects of the match. In addition, the AFMC received feedback from [&hellip;]","og_url":"https:\/\/www.afmc.ca\/fr\/learners-news-november-2023\/","og_site_name":"AFMC","article_published_time":"2023-11-15T19:33:38+00:00","author":"Fatou Thioune","twitter_card":"summary_large_image","twitter_creator":"@AFMC_e","twitter_site":"@AFMC_e","twitter_misc":{"\u00c9crit par":"Fatou Thioune","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.afmc.ca\/learners-news-november-2023\/#article","isPartOf":{"@id":"https:\/\/www.afmc.ca\/learners-news-november-2023\/"},"author":{"name":"Fatou Thioune","@id":"https:\/\/www.afmc.ca\/#\/schema\/person\/e8e6ce9828f441168a40cdf0d821bab2"},"headline":"Learners News: November 2023\u00a0","datePublished":"2023-11-15T19:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.afmc.ca\/learners-news-november-2023\/"},"wordCount":1017,"publisher":{"@id":"https:\/\/www.afmc.ca\/#organization"},"keywords":["Learners"],"articleSection":["News"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.afmc.ca\/learners-news-november-2023\/","url":"https:\/\/www.afmc.ca\/learners-news-november-2023\/","name":"Learners News: November 2023\u00a0 - AFMC","isPartOf":{"@id":"https:\/\/www.afmc.ca\/#website"},"datePublished":"2023-11-15T19:33:38+00:00","breadcrumb":{"@id":"https:\/\/www.afmc.ca\/learners-news-november-2023\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.afmc.ca\/learners-news-november-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.afmc.ca\/learners-news-november-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.afmc.ca\/"},{"@type":"ListItem","position":2,"name":"Learners News: November 2023\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.afmc.ca\/#website","url":"https:\/\/www.afmc.ca\/","name":"l\u2019AFMC","description":"The academic partner for Canada\u2019s faculties of medicine.","publisher":{"@id":"https:\/\/www.afmc.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.afmc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.afmc.ca\/#organization","name":"Association des facult\u00e9s de m\u00e9decine du Canada","url":"https:\/\/www.afmc.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.afmc.ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/09\/AFMC-Flywheel.jpg","contentUrl":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/09\/AFMC-Flywheel.jpg","width":904,"height":536,"caption":"The Association of Faculties of Medicine of Canada"},"image":{"@id":"https:\/\/www.afmc.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AFMC_e","https:\/\/www.instagram.com\/afmc.ca\/","https:\/\/www.linkedin.com\/company\/the-association-of-faculties-of-medicine-of-canada\/?originalSubdomain=ca","https:\/\/www.youtube.com\/channel\/UC02Np2Hp_mw-Tr5gR_y24pg?view_as=subscriber","https:\/\/twitter.com\/AFMC_f"]},{"@type":"Person","@id":"https:\/\/www.afmc.ca\/#\/schema\/person\/e8e6ce9828f441168a40cdf0d821bab2","name":"Fatou Thioune","url":"https:\/\/www.afmc.ca\/fr\/author\/fthiouneafmc-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/8898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/comments?post=8898"}],"version-history":[{"count":5,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/8898\/revisions"}],"predecessor-version":[{"id":8903,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/8898\/revisions\/8903"}],"wp:attachment":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/media?parent=8898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/categories?post=8898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/tags?post=8898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}