{"id":934,"date":"2022-10-01T12:00:00","date_gmt":"2022-10-01T16:00:00","guid":{"rendered":"https:\/\/www.afmc.ca\/?p=934"},"modified":"2022-10-22T16:35:42","modified_gmt":"2022-10-22T20:35:42","slug":"afmc-student-questionnaires-surveys-are-live-and-results-are-in","status":"publish","type":"post","link":"https:\/\/www.afmc.ca\/fr\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/","title":{"rendered":"Questionnaires \u00e0 l\u2019intention des \u00e9tudiants de l'AFMC : Les questionnaires sont en ligne et les r\u00e9sultats sont arriv\u00e9s!"},"content":{"rendered":"<p>The AFMC Student Questionnaires are a series of surveys created by our Canadian Medical Education leaders given to MD students at the most appropriate times during their MD journey. Students are asked about their experiences at the start of medical school with the MD Entry Survey, halfway through with the PreClerkship Survey and at the end with the Graduation Questionnaire.\u00a0 The information collected about the student experience is aggregated for privacy and provided to the faculties to improve their programs.\u00a0 Student opinions matter and their feedback is crucial to effect change. We are very appreciative of the time taken by students to complete these surveys.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Le Questionnaire \u00e0 l\u2019intention des nouveaux \u00e9tudiants et le Questionnaire sur le pr\u00e9externat sont maintenant en ligne.<\/strong> Les \u00e9tudiants devraient avoir re\u00e7u un courriel de l'AFMC contenant un lien pour r\u00e9pondre au questionnaire pertinent. Ils ont jusqu'au 24 octobre pour participer.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Les rapports aff\u00e9rents \u00e0 l\u2019\u00e9dition 2022 du Questionnaire \u00e0 l\u2019intention des dipl\u00f4m\u00e9s sont maintenant disponibles.<\/strong> Les r\u00e9sultats de l\u2019enqu\u00eate de cette ann\u00e9e r\u00e9v\u00e8lent le travail positif des facult\u00e9s en mati\u00e8re de sensibilisation aux politiques facultaires relatives au harc\u00e8lement et \u00e0 l\u2019intimidation. Pour la premi\u00e8re fois, 100 % des r\u00e9pondants ont indiqu\u00e9 \u00eatre au courant de la politique de leur facult\u00e9 concernant le harc\u00e8lement\/l\u2019intimidation dont sont victimes les \u00e9tudiants en m\u00e9decine et conna\u00eetre la proc\u00e9dure \u00e0 suivre dans leur facult\u00e9 pour signaler de tels cas. Il s'agit d'une grande am\u00e9lioration par rapport aux deux ann\u00e9es pr\u00e9c\u00e9dentes, o\u00f9 seulement 85 % des \u00e9tudiants avaient d\u00e9clar\u00e9 conna\u00eetre la proc\u00e9dure de leur facult\u00e9 pour signaler ce type de situations.<\/p>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"975\" src=\"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletterFR.jpg\" alt=\"\" class=\"wp-image-935\" srcset=\"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletterFR.jpg 1836w, https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletterFR-300x286.jpg 300w, https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletterFR-1024x975.jpg 1024w, https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletterFR-768x732.jpg 768w, https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletterFR-1536x1463.jpg 1536w, https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletterFR-13x12.jpg 13w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Les deux derni\u00e8res ann\u00e9es ont \u00e9t\u00e9 marqu\u00e9es par des d\u00e9fis et des changements dans l'enseignement m\u00e9dical en raison de la pand\u00e9mie. Nous sommes heureux d'annoncer que presque tous les \u00e9tudiants (94,5 %) \u00e9taient d'accord\/tout \u00e0 fait d'accord pour dire qu'ils sont convaincus d'avoir d\u00e9velopp\u00e9 les comp\u00e9tences cliniques requises pour commencer un programme de r\u00e9sidence. De plus, en m\u00e9decine familiale, 94,6 % des \u00e9tudiants \u00e9taient d'accord ou tout \u00e0 fait d'accord pour dire qu'ils avaient un acc\u00e8s suffisant \u00e0 la vari\u00e9t\u00e9 de patients et de proc\u00e9dures n\u00e9cessaires pour remplir leur journal de rencontres. Il s'agit d'une augmentation par rapport \u00e0 93,3 % en 2021.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>There has been a slight decrease in feeling well trained and prepared to deliver culturally competent care over previous years. Most students (83%) agreed or strongly agreed that they were appropriately trained to care for individuals from diverse backgrounds and felt prepared to provide culturally competent care.\u00a0 This may be due to more awareness of what culturally competent means and the impact it can have on practice.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En ce qui concerne la planification de carri\u00e8re, les \u00e9tudiants ont indiqu\u00e9 ces derni\u00e8res ann\u00e9es qu'ils souhaitaient \u00eatre mieux inform\u00e9s sur l'\u00e9volution de l'environnement professionnel. Cette tendance s'est accentu\u00e9e au cours de la p\u00e9riode de pand\u00e9mie.\u00a0<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Le montant m\u00e9dian de la dette qui a \u00e9t\u00e9 accumul\u00e9e directement pour les \u00e9tudes en m\u00e9decine de cette classe de dipl\u00f4m\u00e9s est de 90 000 $. Si l'on examine le haut de cette \u00e9chelle, 12 % des \u00e9tudiants ont d\u00e9clar\u00e9 avoir une dette de plus de 200 000 $.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Lire la version compl\u00e8te du Questionnaire \u00e0 l\u2019intention des dipl\u00f4m\u00e9s. (Avenir bient\u00f4t !)<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>L'\u00e9quipe des Services des donn\u00e9es et de l'information de l'AFMC est responsable de la distribution et de la collecte des enqu\u00eates annuelles. Les renseignements recueillis dans le cadre de ces enqu\u00eates confidentielles peuvent \u00eatre utilis\u00e9s pour r\u00e9pondre aux pr\u00e9occupations des apprenants et am\u00e9liorer les programmes d'admission, d'accueil, d'\u00e9ducation et les programmes cliniques des facult\u00e9s de m\u00e9decine.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Des questions? N\u2019h\u00e9sitez pas \u00e0 communiquer avec l'\u00e9quipe des Services des donn\u00e9es et de l'information de l'AFMC \u00e0 l'adresse <a href=\"mailto:data@afmc.ca\">data@afmc.ca<\/a><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Les questionnaires \u00e0 l\u2019intention des \u00e9tudiants de l'AFMC sont une s\u00e9rie d'enqu\u00eates cr\u00e9\u00e9es par les responsables de l'\u00e9ducation m\u00e9dicale au Canada et remises aux \u00e9tudiants en m\u00e9decine aux moments les plus appropri\u00e9s de leur parcours.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[13,12],"class_list":["post-934","post","type-post","status-publish","format-standard","hentry","category-news","tag-faculty","tag-learners"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AFMC Student Questionnaires: Surveys are live and results are in! - AFMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.afmc.ca\/fr\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFMC Student Questionnaires: Surveys are live and results are in! - AFMC\" \/>\n<meta property=\"og:description\" content=\"The AFMC Student Questionnaires are a series of surveys created by our Canadian Medical Education leaders given to MD students at the most appropriate times during their MD journey.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.afmc.ca\/fr\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/\" \/>\n<meta property=\"og:site_name\" content=\"AFMC\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-01T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-22T20:35:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletter-1024x975.jpg\" \/>\n<meta name=\"author\" content=\"Marie Scharfe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AFMC_e\" \/>\n<meta name=\"twitter:site\" content=\"@AFMC_e\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Scharfe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/\"},\"author\":{\"name\":\"Marie Scharfe\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/person\\\/88e91e83adead2b76f1ad4abfb5343f9\"},\"headline\":\"AFMC Student Questionnaires: Surveys are live and results are in!\",\"datePublished\":\"2022-10-01T16:00:00+00:00\",\"dateModified\":\"2022-10-22T20:35:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/\"},\"wordCount\":522,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/GQ-Infographic_sepnewsletter-1024x975.jpg\",\"keywords\":[\"Faculty\",\"Learners\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/\",\"name\":\"AFMC Student Questionnaires: Surveys are live and results are in! - AFMC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/GQ-Infographic_sepnewsletter-1024x975.jpg\",\"datePublished\":\"2022-10-01T16:00:00+00:00\",\"dateModified\":\"2022-10-22T20:35:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/GQ-Infographic_sepnewsletter-1024x975.jpg\",\"contentUrl\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/GQ-Infographic_sepnewsletter-1024x975.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.afmc.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AFMC Student Questionnaires: Surveys are live and results are in!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/\",\"name\":\"AFMC\",\"description\":\"The academic partner for Canada\u2019s faculties of medicine.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.afmc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#organization\",\"name\":\"The Association of Faculties of Medicine of Canada\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AFMC-Flywheel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.afmc.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/AFMC-Flywheel.jpg\",\"width\":904,\"height\":536,\"caption\":\"The Association of Faculties of Medicine of Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AFMC_e\",\"https:\\\/\\\/www.instagram.com\\\/afmc.ca\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/the-association-of-faculties-of-medicine-of-canada\\\/?originalSubdomain=ca\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC02Np2Hp_mw-Tr5gR_y24pg?view_as=subscriber\",\"https:\\\/\\\/twitter.com\\\/AFMC_f\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.afmc.ca\\\/#\\\/schema\\\/person\\\/88e91e83adead2b76f1ad4abfb5343f9\",\"name\":\"Marie Scharfe\",\"sameAs\":[\"https:\\\/\\\/www.afmc.ca\"],\"url\":\"https:\\\/\\\/www.afmc.ca\\\/fr\\\/author\\\/marie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AFMC Student Questionnaires: Surveys are live and results are in! - AFMC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.afmc.ca\/fr\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/","og_locale":"fr_CA","og_type":"article","og_title":"AFMC Student Questionnaires: Surveys are live and results are in! - AFMC","og_description":"The AFMC Student Questionnaires are a series of surveys created by our Canadian Medical Education leaders given to MD students at the most appropriate times during their MD journey.","og_url":"https:\/\/www.afmc.ca\/fr\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/","og_site_name":"AFMC","article_published_time":"2022-10-01T16:00:00+00:00","article_modified_time":"2022-10-22T20:35:42+00:00","og_image":[{"url":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletter-1024x975.jpg","type":"","width":"","height":""}],"author":"Marie Scharfe","twitter_card":"summary_large_image","twitter_creator":"@AFMC_e","twitter_site":"@AFMC_e","twitter_misc":{"\u00c9crit par":"Marie Scharfe","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/#article","isPartOf":{"@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/"},"author":{"name":"Marie Scharfe","@id":"https:\/\/www.afmc.ca\/#\/schema\/person\/88e91e83adead2b76f1ad4abfb5343f9"},"headline":"AFMC Student Questionnaires: Surveys are live and results are in!","datePublished":"2022-10-01T16:00:00+00:00","dateModified":"2022-10-22T20:35:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/"},"wordCount":522,"commentCount":0,"publisher":{"@id":"https:\/\/www.afmc.ca\/#organization"},"image":{"@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/#primaryimage"},"thumbnailUrl":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletter-1024x975.jpg","keywords":["Faculty","Learners"],"articleSection":["News"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/","url":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/","name":"AFMC Student Questionnaires: Surveys are live and results are in! - AFMC","isPartOf":{"@id":"https:\/\/www.afmc.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/#primaryimage"},"image":{"@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/#primaryimage"},"thumbnailUrl":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletter-1024x975.jpg","datePublished":"2022-10-01T16:00:00+00:00","dateModified":"2022-10-22T20:35:42+00:00","breadcrumb":{"@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/#primaryimage","url":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletter-1024x975.jpg","contentUrl":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/10\/GQ-Infographic_sepnewsletter-1024x975.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.afmc.ca\/afmc-student-questionnaires-surveys-are-live-and-results-are-in\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.afmc.ca\/"},{"@type":"ListItem","position":2,"name":"AFMC Student Questionnaires: Surveys are live and results are in!"}]},{"@type":"WebSite","@id":"https:\/\/www.afmc.ca\/#website","url":"https:\/\/www.afmc.ca\/","name":"l\u2019AFMC","description":"The academic partner for Canada\u2019s faculties of medicine.","publisher":{"@id":"https:\/\/www.afmc.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.afmc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.afmc.ca\/#organization","name":"Association des facult\u00e9s de m\u00e9decine du Canada","url":"https:\/\/www.afmc.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.afmc.ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/09\/AFMC-Flywheel.jpg","contentUrl":"https:\/\/www.afmc.ca\/wp-content\/uploads\/2022\/09\/AFMC-Flywheel.jpg","width":904,"height":536,"caption":"The Association of Faculties of Medicine of Canada"},"image":{"@id":"https:\/\/www.afmc.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AFMC_e","https:\/\/www.instagram.com\/afmc.ca\/","https:\/\/www.linkedin.com\/company\/the-association-of-faculties-of-medicine-of-canada\/?originalSubdomain=ca","https:\/\/www.youtube.com\/channel\/UC02Np2Hp_mw-Tr5gR_y24pg?view_as=subscriber","https:\/\/twitter.com\/AFMC_f"]},{"@type":"Person","@id":"https:\/\/www.afmc.ca\/#\/schema\/person\/88e91e83adead2b76f1ad4abfb5343f9","name":"Marie Scharfe","sameAs":["https:\/\/www.afmc.ca"],"url":"https:\/\/www.afmc.ca\/fr\/author\/marie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/comments?post=934"}],"version-history":[{"count":5,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/934\/revisions"}],"predecessor-version":[{"id":4328,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/posts\/934\/revisions\/4328"}],"wp:attachment":[{"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/media?parent=934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/categories?post=934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.afmc.ca\/fr\/wp-json\/wp\/v2\/tags?post=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}